{"id":1983,"date":"2020-02-28T14:56:38","date_gmt":"2020-02-28T14:56:38","guid":{"rendered":"https:\/\/galeria-ipanema.com\/?page_id=1983"},"modified":"2020-02-28T14:56:38","modified_gmt":"2020-02-28T14:56:38","slug":"ibere-camargo","status":"publish","type":"page","link":"https:\/\/galeria-ipanema.com\/en\/ibere-camargo\/","title":{"rendered":"Iber\u00ea Camargo"},"content":{"rendered":"<figure class=\"wp-block-image size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"1984\" data-permalink=\"https:\/\/galeria-ipanema.com\/en\/ibere-camargo\/ibere-camargo\/\" data-orig-file=\"https:\/\/i0.wp.com\/galeria-ipanema.com\/wp-content\/uploads\/2020\/02\/Ibere-camargo.jpg?fit=277%2C255&amp;ssl=1\" data-orig-size=\"277,255\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Ibere-camargo\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/galeria-ipanema.com\/wp-content\/uploads\/2020\/02\/Ibere-camargo.jpg?fit=277%2C255&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/galeria-ipanema.com\/wp-content\/uploads\/2020\/02\/Ibere-camargo.jpg?resize=352%2C324&#038;ssl=1\" alt=\"\" class=\"wp-image-1984\" width=\"352\" height=\"324\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>BIOGRAFIA<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Iber\u00ea Bassani de Camargo (Restinga Seca RS 1914 &#8211; Porto Alegre RS 1994). Pintor, gravador, desenhista, escritor e professor. Em 1928 estuda pintura com Frederico Lobe e Salvador Parlagreco (1871 &#8211; 1953) na Escola de Artes e Of\u00edcios, em Santa Maria, Rio Grande do Sul. Entre 1936 e 1939, em Porto Alegre, faz o curso t\u00e9cnico de arquitetura do Instituto de Belas Artes de Porto Alegre e estuda pintura com Fahrion (1898 &#8211; 1970). Muda-se para o Rio de Janeiro em 1942 e, com bolsa de estudos concedida pelo governo do Rio Grande do Sul, freq\u00fcenta por pouco tempo a Escola Nacional de Belas Artes &#8211; Enba. N\u00e3o satisfeito com a proposta acad\u00eamica, estuda com Guignard (1896 &#8211; 1962) e funda, em 1943, com outros artistas, o Grupo Guignard. Em 1947 recebe o pr\u00eamio de viagem ao exterior e vai para a Europa no ano seguinte. Em Roma, estuda com Giorgio de Chirico (1888 &#8211; 1978), Carlos Alberto Petrucci, Ant\u00f4nio Achille e Leone Augusto Rosa, e em Paris, com Andr\u00e9 Lhote (1885 &#8211; 1962). Volta ao Brasil em 1950 e, em 1952, torna-se membro da Comiss\u00e3o Nacional de Artes Pl\u00e1sticas. Funda, em 1953, o curso de gravura do Instituto Municipal de Belas Artes do Rio de Janeiro, hoje Escola de Artes Visuais do Parque Lage &#8211; EAV\/Parque Lage. Em 1954, participa com Djanira (1914 &#8211; 1979) e Milton Dacosta (1915 &#8211; 1988), da organiza\u00e7\u00e3o do Sal\u00e3o Preto e Branco e, no ano seguinte, do Sal\u00e3o Miniatura, ambos realizados em protesto \u00e0s altas taxas de importa\u00e7\u00e3o de material art\u00edstico. Promove curso livre de pintura no Theatro S\u00e3o Pedro, em Porto Alegre, em duas temporadas entre 1960 e 1965. Em 1966 executa painel de 49 metros quadrados oferecido pelo Brasil \u00e0 Organiza\u00e7\u00e3o Mundial de Sa\u00fade &#8211; OMS, em Genebra. A partir de 1970, leciona na Escola de Belas Artes da Universidade Federal do Rio Grande do Sul &#8211; UFRGS. Em 1980 Iber\u00ea Camargo mata a tiros um homem que o agride na rua. \u00c9 absolvido sob o argumento de leg\u00edtima defesa, mas o epis\u00f3dio marca profundamente sua vida e sua obra. Em 1986, recebe o t\u00edtulo de doutor honoris causa da Universidade Federal de Santa Maria &#8211; UFSM. Entre suas publica\u00e7\u00f5es, constam o artigo Tratado sobre Gravura em Metal, 1964, o livro t\u00e9cnico A Gravura, 1992 e o livro de contos No Andar do Tempo: 9 contos e um esbo\u00e7o autobiogr\u00e1fico, 1988.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>NASCIMENTO \/ MORTE<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">1914 &#8211; Restinga Seca RS &#8211; 18 de novembro<br>1994 &#8211; Porto Alegre RS &#8211; 9 de agosto<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>FORMA\u00c7\u00c3O<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">1927 &#8211; Santa Maria RS &#8211; Estuda no Internato de Santa Maria, Escola Cacequi, e inicia estudos de pintura na Escola de Artes e Of\u00edcios.<br>1928 &#8211; Santa Maria RS &#8211; \u00c9 aluno de pintura de Frederico Lobe e Salvador Parlagreco (1871 &#8211; 1953), na Escola de Artes e Of\u00edcios.<br>1936\/1939 &#8211; Porto Alegre RS &#8211; Curso t\u00e9cnico de arquitetura do Instituto de Belas Artes de Porto Alegre.<br>ca.1936\/ca.1939 &#8211; Porto Alegre RS &#8211; Estuda pintura com Fahrion (1898 &#8211; 1970).<br>1942 &#8211; Rio de Janeiro RJ &#8211; Com bolsa do governo do Estado do Rio Grande do Sul, come\u00e7a a cursar a Enba, por\u00e9m abandona o curso por n\u00e3o tolerar o academismo vigente.<br>1942 &#8211; Rio de Janeiro RJ &#8211; Estuda gravura em metal com Guignard (1896 &#8211; 1962) e Hans Steiner.<br>1943 &#8211; Rio de Janeiro RJ &#8211; Funda, com outros artistas, o Grupo Guignard.<br>1947 &#8211; Rio de Janeiro RJ &#8211; Recebe pr\u00eamio de viagem ao estrangeiro.<br>1948\/1949 &#8211; Roma (It\u00e1lia) &#8211; Estuda com Giorgio de Chirico (1888 &#8211; 1978), Carlos Alberto Petrucci, Ant\u00f4nio Achille e Leone Augusto Rosa.<br>1949\/1950 &#8211; Paris (Fran\u00e7a) &#8211; Estuda com Andr\u00e9 Lhote (1885 &#8211; 1962).<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"248\" data-attachment-id=\"1985\" data-permalink=\"https:\/\/galeria-ipanema.com\/en\/ibere-camargo\/iberecamargo-3\/\" data-orig-file=\"https:\/\/i0.wp.com\/galeria-ipanema.com\/wp-content\/uploads\/2020\/02\/iberecamargo-3.jpg?fit=745%2C352&amp;ssl=1\" data-orig-size=\"745,352\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"iberecamargo-3\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/galeria-ipanema.com\/wp-content\/uploads\/2020\/02\/iberecamargo-3.jpg?fit=525%2C248&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/galeria-ipanema.com\/wp-content\/uploads\/2020\/02\/iberecamargo-3.jpg?resize=525%2C248&#038;ssl=1\" alt=\"\" class=\"wp-image-1985\" srcset=\"https:\/\/i0.wp.com\/galeria-ipanema.com\/wp-content\/uploads\/2020\/02\/iberecamargo-3.jpg?w=745&amp;ssl=1 745w, https:\/\/i0.wp.com\/galeria-ipanema.com\/wp-content\/uploads\/2020\/02\/iberecamargo-3.jpg?resize=300%2C142&amp;ssl=1 300w\" sizes=\"auto, (max-width: 706px) 89vw, (max-width: 767px) 82vw, 740px\" \/><figcaption>Iber\u00ea Camargo &#8211; Espa\u00e7o com Carret\u00e9is &#8211; \u00d3leo sobre tela &#8211; 100 x 140 cm &#8211; 1960<br><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>CRONOLOGIA<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Pintor, gravador, professor, desenhista e escritor<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>ca.1920\/1936 &#8211; Santa Maria RS &#8211; Fixa resid\u00eancia<\/li><li>ca.1936\/1942 &#8211; Porto Alegre RS &#8211; Fixa resid\u00eancia<\/li><li>1942\/1982 &#8211; Rio de Janeiro RJ &#8211; Fixa resid\u00eancia<\/li><li>1948\/1950 &#8211; Europa &#8211; Bolsa de estudo<\/li><li>1952\/1955 &#8211; Rio de Janeiro RJ &#8211; Membro da Comiss\u00e3o Nacional de Belas Artes<\/li><li>1952 &#8211; Rio de Janeiro RJ &#8211; Realiza gravuras para ilustrar o livro O Rebelde, de Ingl\u00eas de Sousa<\/li><li>1953 &#8211; Rio de Janeiro RJ &#8211; Funda o curso de gravura em metal, no Instituto Municipal de Belas Artes<\/li><li>1955 &#8211; Rio de Janeiro RJ &#8211; Idealizou o Sal\u00e3o Miniatura em protesto \u00e0s altas taxas de importa\u00e7\u00e3o de tintas, na ABI<\/li><li>1960 &#8211; Montevid\u00e9u (Uruguai) &#8211; Convidado pelo Itamaraty a ministrar curso sobre gravura em metal nessa cidade<\/li><li>1960 &#8211; Porto Alegre RS &#8211; Curso de pintura na Prefeitura de Porto Alegre, origem do Ateli\u00ea Livre da Municipalidade<\/li><li>1962 &#8211; Rio de Janeiro RJ &#8211; Fecha contrato para fazer dois pain\u00e9is de grandes propor\u00e7\u00f5es para a Cia. de Navega\u00e7\u00e3o Costeira<\/li><li>1964 &#8211; Rio de Janeiro RJ &#8211; Publica nos Cadernos Brasileiros o seu Tratado sobre Gravura em Metal<\/li><li>1965 &#8211; Porto Alegre RS &#8211; \u00c9 professor convidado na Escola de Belas Artes da UFRGS<\/li><li>1966 &#8211; Genebra (Su\u00ed\u00e7a) &#8211; Executa painel de 49 m2 oferecido pelo Brasil \u00e0 OMS, em Genebra<\/li><li>1970 &#8211; Porto Alegre RS &#8211; recebe o t\u00edtulo Cidad\u00e3o de Porto Alegre, concedido pela C\u00e2mara Municipal<\/li><li>1974 &#8211; Santa Maria RS &#8211; Inaugura\u00e7\u00e3o da Galeria Iber\u00ea Camargo, no Diret\u00f3rio Acad\u00eamico da Universidade Federal de Santa Maria<\/li><li>1982 &#8211; Rio de Janeiro RJ &#8211; Finalizado curta-metragem sobre sua obra, por M\u00e1rio Carneiro e Embrafilme<\/li><li>1982\/1994 &#8211; Porto Alegre RS &#8211; Passa a dividir seu tempo entre esta cidade e o Rio de Janeiro<\/li><li>1984 &#8211; Rio de Janeiro RJ &#8211; Realiza dois pain\u00e9is para a Funarte<\/li><li>1985 &#8211; Rio de Janeiro RJ &#8211; Recebe o Pr\u00eamio Golfinho de Ouro por sua atua\u00e7\u00e3o como artista pl\u00e1stico em 1984, concedido pelo Estado do Rio de Janeiro<\/li><li>1985 &#8211; Lan\u00e7amento de livro sobre sua vida e obra, editado pelo Margs, pela Funarte e pelo Minist\u00e9rio da Cultura<\/li><li>1985 &#8211; Porto Alegre RS &#8211; Recebe medalha M\u00e9rito Cultural concedida pela Prefeitura de Porto Alegre<\/li><li>1986 &#8211; Santa Maria RS &#8211; Recebe t\u00edtulo de Doutor Honoris Causa da Universidade Federal de Santa Maria<\/li><li>1988 &#8211; Porto Alegre RS &#8211; Lan\u00e7a livro de contos, com ensaio autobiogr\u00e1fico No Andar do Tempo: 9 contos e um esbo\u00e7o autobiogr\u00e1fico, L&amp;PM Editores<\/li><li>1992 &#8211; Porto Alegre RS &#8211; Lan\u00e7a livro t\u00e9cnico A Gravura pela Editora Sagra<\/li><li>1994 &#8211; Porto Alegre RS &#8211; Lan\u00e7amento do livro Conversa\u00e7\u00f5es com Iber\u00ea Camargo, de Lisette Lagnado, na Galeria Tina Zappoli<\/li><li>1994 &#8211; S\u00e3o Paulo SP &#8211; Lan\u00e7amento do curta sobre Iber\u00ea Camargo O Pintor, de Joel Pizzini, no Museu de Arte Contempor\u00e2nea da Universidade de S\u00e3o Paulo &#8211; MAC\/USP<\/li><li>1995 &#8211; Porto Alegre RS &#8211; Cria\u00e7\u00e3o da Funda\u00e7\u00e3o Iber\u00ea Camargo<\/li><li>1998 &#8211; S\u00e3o Paulo SP &#8211; Lan\u00e7amento do livro Gaveta dos Guardados, conjunto de textos autobiogr\u00e1ficos organizado por Augusto Massi<\/li><li>1999 &#8211; Rio de Janeiro RJ &#8211; Lan\u00e7amento do livro de correspond\u00eancias entre Iber\u00ea Camargo e M\u00e1rio Carneiro<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>EXPOSI\u00c7\u00d5ES INDIVIDUAIS<\/strong><\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>1942 &#8211; Porto Alegre RS &#8211; Individual, no Pal\u00e1cio do Governo<\/li><li>1944 &#8211; Porto Alegre RS &#8211; Individual, na Galeria de Arte Casa das Molduras<\/li><li>1946 &#8211; Rio de Janeiro RJ &#8211; Individual, no Minist\u00e9rio da Educa\u00e7\u00e3o e Sa\u00fade<\/li><li>1947 &#8211; Porto Alegre RS &#8211; Individual, na Galeria de Arte Casa das Molduras<\/li><li>1951 &#8211; Resende RJ &#8211; Individual, no MAM\/Resende<\/li><li>1952 &#8211; Rio de Janeiro RJ &#8211; Individual, na Biblioteca Nacional<\/li><li>1954 &#8211; Rio de Janeiro RJ &#8211; Individual, na Galeria Ibeu Copacabana<\/li><li>1955 &#8211; Porto Alegre RS &#8211; Individual, no Clube de Gravura<\/li><li>1958 &#8211; Rio de Janeiro RJ &#8211; Individual, na Galeria GEA<\/li><li>1959 &#8211; Washington (Estados Unidos) &#8211; Individual, na Pan American Union Gallery<\/li><li>1960 &#8211; Montevid\u00e9u (Uruguai) &#8211; Individual, no Centro de Artes e Letras<\/li><li>1960 &#8211; Porto Alegre RS &#8211; Individual, no Margs<\/li><li>1962 &#8211; Rio de Janeiro RJ &#8211; Exposi\u00e7\u00e3o dos Pain\u00e9is Realizados para Cia. de Navega\u00e7\u00e3o Costeira, no MAM\/RJ<\/li><li>1962 &#8211; Rio de Janeiro RJ &#8211; Iber\u00ea Camargo: retrospectiva, no MAM\/RJ<\/li><li>1963 &#8211; Rio de Janeiro RJ &#8211; Individual, na Petite Galerie<\/li><li>1964 &#8211; Rio de Janeiro RJ &#8211; Individual, na Galeria Bonino<\/li><li>1965 &#8211; Rio de Janeiro RJ &#8211; Individual, na Galeria Bonino<\/li><li>1966 &#8211; Rio de Janeiro RJ &#8211; Individual, na Galeria Bonino<\/li><li>1969 &#8211; Porto Alegre &#8211; Individual, no Instituto de Idiomas Yazigi<\/li><li>1969 &#8211; Santa Maria RS &#8211; Individual, na Biblioteca Municipal<\/li><li>1970 &#8211; Rio de Janeiro RJ &#8211; Individual, na Gabinete de Arte de Botafogo<\/li><li>1970 &#8211; Rio de Janeiro RJ &#8211; Individual, na Galeria Barcinsky<\/li><li>1972 &#8211; Rio de Janeiro RJ &#8211; Individual, no Atelier do Artista<\/li><li>1973 &#8211; Londres (Inglaterra) &#8211; Individual, na O&#8217;Hana Gallery<\/li><li>1973 &#8211; Porto Alegre RS &#8211; Individual, na Galeria Ianeli<\/li><li>1973 &#8211; Rio de Janeiro RJ &#8211; Individual, na Galeria Maison de France<\/li><li>1974 &#8211; Rio de Janeiro RJ &#8211; Individual, na Galeria Alian\u00e7a Francesa<\/li><li>1975 &#8211; Rio de Janeiro RJ &#8211; Individual, na Galeria Luiz Buarque de Holanda e Paulo Bittencourt<\/li><li>1976 &#8211; Rio de Janeiro RJ &#8211; Individual, na Galeria Bonino<\/li><li>1977 &#8211; Porto Alegre RS &#8211; Individual, na Galeria Oficina de Arte<\/li><li>1977 &#8211; Santa Maria RS &#8211; Individual, na Galeria Iber\u00ea Camargo<\/li><li>1978 &#8211; S\u00e3o Paulo SP &#8211; Individual, na Cristina Faria de Paula Galeria de Arte<\/li><li>1979 &#8211; Paris (Fran\u00e7a) &#8211; Individual, na Galerie Debret<\/li><li>1979 &#8211; Porto Alegre RS &#8211; Individual, no Margs<\/li><li>1979 &#8211; Rio de Janeiro RJ &#8211; Individual, na Galeria de Arte Ipanema<\/li><li>1980 &#8211; Curitiba PR &#8211; Iber\u00ea Camargo: retrospectiva de desenhos, na Biblioteca Museu Guido Viaro<\/li><li>1980 &#8211; Porto Alegre RS &#8211; Iber\u00ea Camargo: retrospectiva de desenhos, no Margs<\/li><li>1980 &#8211; Porto Alegre RS &#8211; Individual, na Galeria do Centro Comercial<\/li><li>1981 &#8211; Porto Alegre RS &#8211; Individual, na Galeria do Centro Comercial<\/li><li>1981 &#8211; Rio de Janeiro RJ &#8211; Individual, na Acervo Galeria de Arte<\/li><li>1982 &#8211; Porto Alegre RS &#8211; Individual, no Margs<\/li><li>1982 &#8211; Rio de Janeiro RJ &#8211; Individual, no Cl\u00e1udio Gil Studio de Arte<\/li><li>1983 &#8211; Porto Alegre RS &#8211; Individual, na Galeria Tina Presser<\/li><li>1984 &#8211; Fortaleza CE &#8211; Iber\u00ea Camargo: desenhos, pinturas e gravuras, na Galeria Multiarte<\/li><li>1984 &#8211; Porto Alegre RS &#8211; Iber\u00ea Camargo, Aquele Abra\u00e7o!, no Centro Municipal de Cultura &#8211; exposi\u00e7\u00e3o iconogr\u00e1fica comemorativa ao seu 70\u00ba anivers\u00e1rio<\/li><li>1984 &#8211; Porto Alegre RS &#8211; Iber\u00ea Camargo: retrospectiva, no Margs<\/li><li>1984 &#8211; Porto Alegre RS &#8211; Individual, na Galeria Tina Presser<\/li><li>1984 &#8211; Rio de Janeiro RJ &#8211; Individual, na Thomas Cohn Arte Contempor\u00e2nea<\/li><li>1984 &#8211; Rio de Janeiro RJ &#8211; Individual, no Cl\u00e1udio Gil Studio de Arte<\/li><li>1984 &#8211; Santa Maria RS &#8211; Individual, na UFSM. Centro de Artes e Letras &#8211; comemorativa ao seu 70\u00ba anivers\u00e1rio<\/li><li>1984 &#8211; S\u00e3o Paulo SP &#8211; Individual, na Galeria Luisa Strina<\/li><li>1985 &#8211; Porto Alegre RS &#8211; Iber\u00ea Camargo: trajet\u00f3rias e encontros, no Margs<\/li><li>1986 &#8211; Curitiba PR &#8211; Individual, na Galeria Max Stolz<\/li><li>1986 &#8211; Porto Alegre RS &#8211; Individual, na Galeria Tina Presser<\/li><li>1986 &#8211; Rio de Janeiro RJ &#8211; Individual, no MAM\/RJ<\/li><li>1986 &#8211; S\u00e3o Paulo SP &#8211; Individual, no Masp<\/li><li>1986 &#8211; Vit\u00f3ria ES &#8211; Individual, na Galeria Usina<\/li><li>1987 &#8211; Bras\u00edlia DF &#8211; Individual, no Espa\u00e7o Capital Arte Contempor\u00e2nea<\/li><li>1987 &#8211; Campo Grande MS &#8211; Individual, na Galeria Art-Con<\/li><li>1987 &#8211; Caxias do Sul RS &#8211; Individual, na Galeria Soluzzione<\/li><li>1987 &#8211; Florian\u00f3polis SC &#8211; Individual, na Galeria Espa\u00e7o de Arte<\/li><li>1987 &#8211; Montevid\u00e9u (Uruguai) &#8211; Individual, no Centro de Exposi\u00e7\u00f5es do Departamento Cultural<\/li><li>1987 &#8211; Pelotas RS &#8211; Individual, na Galeria Van Gogh<\/li><li>1987 &#8211; Porto Alegre RS &#8211; Individual, na Galeria Tina Presser<\/li><li>1987 &#8211; Rio de Janeiro RJ &#8211; Individual, na Galeria Paulo Klabin<\/li><li>1987 &#8211; Santa Maria RS &#8211; Individual, na Galeria Matiz<\/li><li>1987 &#8211; S\u00e3o Paulo SP &#8211; Individual, na Galeria Luisa Strina<\/li><li>1987 &#8211; S\u00e3o Paulo SP &#8211; Individual, na Galeria Montesanti Roesler<\/li><li>1987 &#8211; S\u00e3o Paulo SP &#8211; Individual, na Galeria Paulo Klabin<\/li><li>1987 &#8211; Uberaba MG &#8211; Individual, na M. D. Galeria de Arte<\/li><li>1988 &#8211; Aracaju SE &#8211; Individual, na Galeria Alvaro Santos<\/li><li>1988 &#8211; Pelotas RS &#8211; Individual, na Galeria Van Gogh<\/li><li>1988 &#8211; Porto Alegre RS &#8211; Individual, na Galeria Tina Zappoli<\/li><li>1988 &#8211; Rio de Janeiro RJ &#8211; Individual, na Galeria Montesanti<\/li><li>1988 &#8211; S\u00e3o Paulo SP &#8211; Individual, na Documenta Galeria de Arte<\/li><li>1989 &#8211; Porto Alegre RS &#8211; Individual, na Galeria Tina Zappoli<\/li><li>1989 &#8211; Porto Alegre RS &#8211; Individual, no Margs<\/li><li>1989 &#8211; Santana do Livramento RS &#8211; Individual, na Galeria Ponto D&#8217;Arte<\/li><li>1990 &#8211; Pelotas RS &#8211; Individual, na Galeria Van Gogh<\/li><li>1990 &#8211; Porto Alegre RS &#8211; A Gravura de Iber\u00ea Camargo: uma retrospectiva, no Espa\u00e7o Cultural BFB<\/li><li>1990 &#8211; Porto Alegre RS &#8211; Individual, na Casa de Cultura Mario Quintana<\/li><li>1990 &#8211; Rio de Janeiro RJ &#8211; A Gravura de Iber\u00ea Camargo: uma retrospectiva, no MNBA<\/li><li>1990 &#8211; Rio de Janeiro RJ &#8211; Individual, na EAV\/Parque Lage<\/li><li>1990 &#8211; Rio de Janeiro RJ &#8211; Individual, no MAM\/RJ<\/li><li>1990 &#8211; S\u00e3o Paulo SP &#8211; A Gravura de Iber\u00ea Camargo: uma retrospectiva, no MAM\/SP<\/li><li>1990 &#8211; S\u00e3o Paulo SP &#8211; Iber\u00ea Camargo: ciclistas no Parque da Reden\u00e7\u00e3o, na Galeria Montesanti Roesler<\/li><li>1991 &#8211; Passo Fundo RS &#8211; Individual, no Espa\u00e7o de Arte<\/li><li>1991 &#8211; Porto Alegre RS &#8211; Individual, no Instituto Goethe<\/li><li>1991 &#8211; Rio de Janeiro RJ &#8211; Individual, na EAV\/Parque Lage<\/li><li>1991 &#8211; S\u00e3o Paulo SP &#8211; A Gravura de Iber\u00ea Camargo: uma retrospectiva, no MAM\/SP<\/li><li>1991 &#8211; S\u00e3o Paulo SP &#8211; Individual, na Galeria Montesanti Roesler<\/li><li>1991 &#8211; S\u00e3o Paulo SP &#8211; Individual, no Masp<\/li><li>1992 &#8211; Fortaleza CE &#8211; Individual, na Galeria Multiarte<\/li><li>1992 &#8211; Porto Alegre RS &#8211; Individual, no Centro Municipal de Cultura<\/li><li>1993 &#8211; Florian\u00f3polis SC &#8211; Iber\u00ea Camargo: pinturas, no Masc<\/li><li>1993 &#8211; Porto Alegre RS &#8211; Iber\u00ea Camargo: retratos de amigos, no Hotel Center Park.<\/li><li>1993 &#8211; Porto Alegre RS &#8211; Individual, na Usina do Gas\u00f4metro<\/li><li>1993 &#8211; Ribeir\u00e3o Preto SP &#8211; Retrospectiva de Gravuras de Iber\u00ea Camargo, no Museu de Arte de Ribeir\u00e3o Preto Pedro Manuel-Gismondi<\/li><li>1993 &#8211; Salvador BA &#8211; Individual, no Escrit\u00f3rio de Arte da Bahia<\/li><li>1993 &#8211; S\u00e3o Paulo SP &#8211; Individual, Galeria Camargo Vila\u00e7a<\/li><li>1994 &#8211; Porto Alegre RS &#8211; Homenagem a Iber\u00ea Camargo, no Margs<\/li><li>1994 &#8211; Porto Alegre RS &#8211; Individual, no Espa\u00e7o Cultural Fiat<\/li><li>1994 &#8211; Rio de Janeiro RJ &#8211; Iber\u00ea Camargo Mestre Moderno, no CCBB<\/li><li>1994 &#8211; S\u00e3o Paulo SP &#8211; Individual, no CCSP. Divis\u00e3o de Artes Pl\u00e1sticas<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>EXPOSI\u00c7\u00d5ES COLETIVAS<\/strong><\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>1943 &#8211; Rio de Janeiro RJ &#8211; Grupo Guignard, no Diret\u00f3rio Acad\u00eamico da Enba (desmontada \u00e0 for\u00e7a por um grupo de alunos da Enba, \u00e9 reinaugurada na ABI)<\/li><li>1944 &#8211; Belo Horizonte MG &#8211; Exposi\u00e7\u00e3o de Arte Moderna, no Edif\u00edcio Mariana<\/li><li>1944 &#8211; Londres (Inglaterra) &#8211; Exhibition of Modern Brazilian Paintings, na Royal Academy of Arts<\/li><li>1944 &#8211; Norwich (Inglaterra) &#8211; Exhibition of Modern Brazilian Paintings, no Norwich Castle and Museum<\/li><li>1944 &#8211; Rio de Janeiro RJ &#8211; 50\u00ba Sal\u00e3o Nacional de Belas Artes &#8211; Divis\u00e3o Moderna, no MNBA<\/li><li>1945 &#8211; Baht (Inglaterra) &#8211; Exhibition of Modern Brazilian Paintings, na Victory Art Gallery<\/li><li>1945 &#8211; Bristol (Inglaterra) &#8211; Exhibition of Modern Brazilian Paintings, no Bristol City Museum &amp; Art Gallery<\/li><li>1945 &#8211; Buenos Aires (Argentina) &#8211; 20 Artistas Brasile\u00f1os, nas Salas Nacionales de Exposici\u00f3n<\/li><li>1945 &#8211; Edimburgo (Esc\u00f3cia) &#8211; Exhibition of Modern Brazilian Paintings, na National Gallery<\/li><li>1945 &#8211; Glasgow (Esc\u00f3cia) &#8211; Exhibition of Modern Brazilian Paintings, na Kelingrove Art Gallery<\/li><li>1945 &#8211; La Plata (Argentina) &#8211; 20 Artistas Brasile\u00f1os, no Museo Provincial de Bellas Artes<\/li><li>1945 &#8211; Manchester (Inglaterra) &#8211; Exhibition of Modern Brazilian Paintings, na Manchester Art Gallery<\/li><li>1945 &#8211; Montevid\u00e9u (Uruguai) &#8211; 20 Artistas Brasile\u00f1os, na Comisi\u00f3n Municipal de Cultura<\/li><li>1945 &#8211; Rio de Janeiro RJ &#8211; 51\u00ba Sal\u00e3o Nacional de Belas Artes, no MNBA<\/li><li>1946 &#8211; Rio de Janeiro RJ &#8211; 52\u00ba Sal\u00e3o Nacional de Belas Artes, no MNBA<\/li><li>1947 &#8211; Montevid\u00e9u (Uruguai) &#8211; Pintura Contempor\u00e2nea Brasileira<\/li><li>1947 &#8211; Rio de Janeiro RJ &#8211; 53\u00ba Sal\u00e3o Nacional de Belas Artes, no MNBA &#8211; pr\u00eamio de viagem ao exterior<\/li><li>1948 &#8211; Johanesburgo (\u00c1frica do Sul) &#8211; Pintura Contempor\u00e2nea Brasileira<\/li><li>1951 &#8211; Madri (Espanha) &#8211; Bienal de Madri<\/li><li>1951 &#8211; S\u00e3o Paulo SP &#8211; 1\u00aa Bienal Internacional de S\u00e3o Paulo, no Pavilh\u00e3o do Trianon<\/li><li>1952 &#8211; Rio de Janeiro RJ &#8211; Exposi\u00e7\u00e3o de Artistas Brasileiros, no MAM\/RJ<\/li><li>1953 &#8211; Porto Alegre RS &#8211; 4\u00ba Sal\u00e3o do Instituto de Belas Artes do Rio Grande do Sul<\/li><li>1953 &#8211; Rio de Janeiro RJ &#8211; 2\u00ba Sal\u00e3o Nacional de Arte Moderna, no MNBA<\/li><li>1954 &#8211; Rio de Janeiro RJ &#8211; Sal\u00e3o Preto e Branco, no Pal\u00e1cio da Cultura<\/li><li>1955 &#8211; Madri (Espanha) &#8211; Bienal de Madri<\/li><li>1955 &#8211; Porto Alegre RS &#8211; Arte Brasileira Contempor\u00e2nea, no Margs<\/li><li>1955 &#8211; Rio de Janeiro RJ &#8211; Sal\u00e3o Carioca<\/li><li>1956 &#8211; Barcelona (Espanha) &#8211; 3\u00aa Bienal HispanoAmericana<\/li><li>1956 &#8211; Nova York (Estados Unidos) &#8211; Coletiva, no Museu Guggenheim<\/li><li>1956 &#8211; Rio de Janeiro RJ &#8211; 5\u00ba Sal\u00e3o Nacional de Arte Moderna<\/li><li>1956 &#8211; S\u00e3o Paulo SP &#8211; 50 Anos de Paisagem Brasileira, no MAM\/SP<\/li><li>1957 &#8211; Buenos Aires (Argentina) &#8211; Arte Moderna no Brasil, no Museo de Arte Moderno<\/li><li>1957 &#8211; Montevid\u00e9u (Uruguai) &#8211; Grabados Brasile\u00f1os, no Instituto de Cultura Uruguayo-Brasile\u00f1o<\/li><li>1957 &#8211; Rio de Janeiro RJ &#8211; 6\u00ba Sal\u00e3o Nacional de Arte Moderna<\/li><li>1958 &#8211; Cidade do M\u00e9xico (M\u00e9xico) &#8211; 1\u00aa Bienal Interamericana de Pintura y Grabado, no Instituto Nacional de Bellas Artes<\/li><li>1958 &#8211; Porto Alegre RS &#8211; 1\u00ba Sal\u00e3o Pan-Americano de Arte<\/li><li>1958 &#8211; Quito (Equador) &#8211; Exposi\u00e7\u00e3o de Gravura Brasileira<\/li><li>1959 &#8211; Rio de Janeiro RJ &#8211; 30 Anos de Arte Brasileira, na Galeria Macuna\u00edma<\/li><li>1959 &#8211; S\u00e3o Paulo SP &#8211; 5\u00aa Bienal Internacional de S\u00e3o Paulo, no Pavilh\u00e3o Ciccilo Matarazzo Sobrinho<\/li><li>1959 &#8211; Washington (Estados Unidos) &#8211; Pan American Union, no Smithsonian Institution<\/li><li>1960 &#8211; Cidade do M\u00e9xico (M\u00e9xico) &#8211; 2\u00aa Bienal Interamericana do M\u00e9xico, no Pal\u00e1cio de Belas Artes<\/li><li>1960 &#8211; Nova York (Estados Unidos) &#8211; Latin American Painters and Painting, no Solomon R. Guggenheim Museum<\/li><li>1960 &#8211; Rio de Janeiro RJ &#8211; 9\u00ba Sal\u00e3o Nacional de Arte Moderna, no MAM\/RJ<\/li><li>1960 &#8211; Rio de Janeiro RJ &#8211; Doze Artistas Brasileiros, na Galeria Bonino<\/li><li>1960 &#8211; T\u00f3quio (Jap\u00e3o) &#8211; International Biennial Exhibition of Prints, no The National Museum of Modern Art<\/li><li>1961 &#8211; Rio de Janeiro RJ &#8211; 1\u00ba O Rosto e a Obra, no Galeria Ibeu Copacabana<\/li><li>1961 &#8211; Rio de Janeiro RJ &#8211; Natureza Morta na Pintura, na Galeria Ibeu Copacabana<\/li><li>1961 &#8211; Rio de Janeiro RJ &#8211; O Rio na Pintura Brasileira, na Biblioteca Estadual da Guanabara<\/li><li>1961 &#8211; S\u00e3o Paulo SP &#8211; 6\u00aa Bienal Internacional de S\u00e3o Paulo, no Pavilh\u00e3o Ciccilo Matarazzo Sobrinho &#8211; pr\u00eamio de melhor pintor nacional<\/li><li>1961 &#8211; T\u00f3quio (Jap\u00e3o) &#8211; 6\u00aa Bienal de T\u00f3quio<\/li><li>1962 &#8211; Minneapolis (Estados Unidos) &#8211; New Art of Brazil, no Walker Art Center<\/li><li>1962 &#8211; Rio de Janeiro RJ &#8211; Exposi\u00e7\u00e3o dos dois pain\u00e9is realizados para Cia. de Navega\u00e7\u00e3o Costeira, no MAM\/RJ<\/li><li>1962 &#8211; S\u00e3o Paulo SP &#8211; Sele\u00e7\u00e3o de Obras de Arte Brasileira da Cole\u00e7\u00e3o Ernesto Wolf, no MAM\/SP<\/li><li>1962 &#8211; Veneza (It\u00e1lia) &#8211; 31\u00aa Bienal de Veneza<\/li><li>1963 &#8211; Rio de Janeiro RJ &#8211; 1\u00ba Resumo de Arte JB, no Jornal do Brasil<\/li><li>1963 &#8211; Rio de Janeiro RJ &#8211; A Paisagem como Tema, na Galeria Ibeu Copacabana<\/li><li>1963 &#8211; S\u00e3o Paulo SP &#8211; 7\u00aa Bienal Internacional de S\u00e3o Paulo, na Funda\u00e7\u00e3o Bienal<\/li><li>1964 &#8211; Rio de Janeiro RJ &#8211; O Nu na Arte Contempor\u00e2nea, na Galeria Ibeu Copacabana<\/li><li>1965 &#8211; Barcelona (Espanha) &#8211; Ocho Grabadores Brasile\u00f1os, na Galer\u00eda Ren\u00e9 Metras<\/li><li>1965 &#8211; Londres (Inglaterra) &#8211; Coletiva, no Royal College of Art<\/li><li>1965 &#8211; Paris (Fran\u00e7a) &#8211; Salon Comparaisons, na Galerie Stubel<\/li><li>1966 &#8211; Austin (Estados Unidos) &#8211; Art of Latin America since Independence, na The University of Texas at Austin. Archer M. Huntington Art Gallery<\/li><li>1966 &#8211; Bonn (Alemanha) &#8211; Brasilianische Kunst Heute<\/li><li>1966 &#8211; Cidade do M\u00e9xico (M\u00e9xico) &#8211; Pintura y Grabado del Brasil, no Museo de Arte Moderno<\/li><li>1966 &#8211; New Haven (Estados Unidos) &#8211; Art of Latin America since Independence, na na The Yale University Art Gallery<\/li><li>1966 &#8211; New Orleans (Estados Unidos) &#8211; Art of Latin America since Independence, no Isaac Delgado Museum of Art<\/li><li>1966 &#8211; Salvador BA &#8211; 1\u00aa Bienal Nacional de Artes Pl\u00e1sticas &#8211; pr\u00eamio aquisi\u00e7\u00e3o<\/li><li>1966 &#8211; San Diego (Estados Unidos) &#8211; Art of Latin America since Independence, no La Jolla Museum of Art<\/li><li>1966 &#8211; San Francisco (Estados Unidos) &#8211; Art of Latin America since Independence, no San Francisco art Museum<\/li><li>1966 &#8211; S\u00e3o Paulo SP &#8211; Meio S\u00e9culo de Arte Nova, no MAC\/USP<\/li><li>1967 &#8211; Rio de Janeiro RJ &#8211; 5\u00ba Resumo de Arte JB, no MAM\/RJ<\/li><li>1968 &#8211; T\u00f3quio (Jap\u00e3o) &#8211; International Biennial Exhibition of Prints<\/li><li>1971 &#8211; Rio de Janeiro RJ &#8211; 9\u00ba Resumo de Arte JB, no MAM\/RJ<\/li><li>1971 &#8211; S\u00e3o Paulo SP &#8211; 11\u00aa Bienal Internacional de S\u00e3o Paulo, na Funda\u00e7\u00e3o Bienal<\/li><li>1972 &#8211; S\u00e3o Paulo SP &#8211; Arte\/Brasil\/Hoje: 50 anos depois, na Galeria da Collectio<\/li><li>1973 &#8211; Liubliana (Iugosl\u00e1via &#8211; atual Eslov\u00eania) &#8211; 10\u00aa Bienal Internacional de Gravura, na Moderna Galerija Ljubljana<\/li><li>1973 &#8211; Rio de Janeiro RJ &#8211; Gravura Brasileira no S\u00e9culo XX, no MNBA<\/li><li>1975 &#8211; Jap\u00e3o &#8211; 2\u00aa Exposi\u00e7\u00e3o de Belas Artes Brasi-Jap\u00e3o, no Centro Lume<\/li><li>1975 &#8211; Rio de Janeiro RJ &#8211; 2\u00aa Exposi\u00e7\u00e3o de Belas Artes Brasi-Jap\u00e3o, no Centro Lume<\/li><li>1975 &#8211; S\u00e3o Paulo SP &#8211; 13\u00aa Bienal Internacional de S\u00e3o Paulo, na Funda\u00e7\u00e3o Bienal<\/li><li>1975 &#8211; S\u00e3o Paulo SP &#8211; 2\u00aa Exposi\u00e7\u00e3o de Belas Artes Brasil-Jap\u00e3o, na Assembl\u00e9ia Legislativa do Estado<\/li><li>1977 &#8211; Belo Horizonte MG &#8211; 5\u00ba Sal\u00e3o Global de Inverno, na Funda\u00e7\u00e3o Pal\u00e1cio das Artes<\/li><li>1977 &#8211; Bras\u00edlia DF &#8211; 5\u00ba Sal\u00e3o Global de Inverno<\/li><li>1977 &#8211; Jap\u00e3o &#8211; 3\u00aa Exposi\u00e7\u00e3o de Belas Artes Brasil-Jap\u00e3o<\/li><li>1977 &#8211; Rio de Janeiro RJ &#8211; 3\u00aa Exposi\u00e7\u00e3o de Belas Artes Brasil-Jap\u00e3o<\/li><li>1977 &#8211; Rio de Janeiro RJ &#8211; 5\u00ba Sal\u00e3o Global de Inverno, no MNBA<\/li><li>1977 &#8211; Roma (It\u00e1lia) &#8211; 10\u00aa Quadriennale Nazionale d&#8217;Arte di Roma<\/li><li>1977 &#8211; S\u00e3o Paulo SP &#8211; 3\u00aa Exposi\u00e7\u00e3o de Belas Artes Brasil-Jap\u00e3o<\/li><li>1977 &#8211; S\u00e3o Paulo SP &#8211; 5\u00ba Sal\u00e3o Global de Inverno, no Masp<\/li><li>1978 &#8211; S\u00e3o Paulo SP &#8211; As Bienais e a Abstra\u00e7\u00e3o: a d\u00e9cada de 50, no Museu Lasar Segall<\/li><li>1979 &#8211; S\u00e3o Paulo SP &#8211; 15\u00aa Bienal Internacional de S\u00e3o Paulo, na Funda\u00e7\u00e3o Bienal<\/li><li>1980 &#8211; Rio de Janeiro RJ &#8211; Homenagem a M\u00e1rio Pedrosa, na Galeria Jean Boghici<\/li><li>1981 &#8211; Osaka (Jap\u00e3o) &#8211; Exposi\u00e7\u00e3o Latino-Americana de Arte Contempor\u00e2nea Brasil\/Jap\u00e3o, no National Museum of Art<\/li><li>1982 &#8211; Lisboa (Portugal) &#8211; Brasil 60 Anos de Arte Moderna: Cole\u00e7\u00e3o Gilberto Chateaubriand, no Centro de Arte Moderna Jos\u00e9 de Azeredo Perdig\u00e3o<\/li><li>1982 &#8211; Londres (Inglaterra) &#8211; Brasil 60 Anos de Arte Moderna: Cole\u00e7\u00e3o Gilberto Chateaubriand, na Barbican Art Gallery<\/li><li>1982 &#8211; Pen\u00e1polis SP &#8211; 5\u00ba Sal\u00e3o de Artes Pl\u00e1sticas da Noroeste, na Funda\u00e7\u00e3o Educacional de Pen\u00e1polis. Faculdade de Filosofia, Ci\u00eancias e Letras de Pen\u00e1polis<\/li><li>1982 &#8211; Porto Alegre RS &#8211; Homenagem a Iber\u00ea Camargo, no Margs<\/li><li>1982 &#8211; Rio de Janeiro RJ &#8211; Entre a Mancha e a Figura, no MAM\/RJ<\/li><li>1983 &#8211; Porto Alegre RS &#8211; Do Passado ao Presente: as artes pl\u00e1sticas no Rio Grande do Sul, no Cambona Centro de Arte<\/li><li>1983 &#8211; Rio de Janeiro RJ &#8211; 3 x 4 Grandes Formatos, na Galeria do Centro Empresarial Rio<\/li><li>1983 &#8211; Rio de Janeiro RJ &#8211; 6\u00ba Sal\u00e3o Nacional de Artes Pl\u00e1sticas, no MAM\/RJ<\/li><li>1983 &#8211; Rio de Janeiro RJ &#8211; Auto-Retratos Brasileiros, na Galeria de Arte Banerj<\/li><li>1984 &#8211; Fortaleza CE &#8211; 7\u00ba Sal\u00e3o Nacional de Artes Pl\u00e1sticas<\/li><li>1984 &#8211; Porto Alegre RS &#8211; Gravuras: uma trajet\u00f3ria no tempo, no Cambona Centro de Arte<\/li><li>1984 &#8211; Ribeir\u00e3o Preto SP &#8211; Gravadores Brasileiros Anos 50\/60, na Galeria Campus USP-Banespa<\/li><li>1984 &#8211; Rio de Janeiro RJ &#8211; 7\u00ba Sal\u00e3o Nacional de Artes Pl\u00e1sticas, no MAM\/RJ<\/li><li>1984 &#8211; Rio de Janeiro RJ &#8211; Interven\u00e7\u00f5es no Espa\u00e7o Urbano, na Funarte. Galeria S\u00e9rgio Milliet<\/li><li>1984 &#8211; Rio de Janeiro RJ &#8211; Pintura Brasileira Atuante, no Espa\u00e7o Petrobras<\/li><li>1984 &#8211; Rio de Janeiro RJ &#8211; Viva a Pintura, na Petite Galerie<\/li><li>1984 &#8211; S\u00e3o Paulo SP &#8211; Cole\u00e7\u00e3o Gilberto Chateaubriand: retrato e autoretrato da arte brasileira, no MAM\/SP<\/li><li>1984 &#8211; S\u00e3o Paulo SP &#8211; Tradi\u00e7\u00e3o e Ruptura: s\u00edntese de arte e cultura brasileiras, na Funda\u00e7\u00e3o Bienal<\/li><li>1985 &#8211; Porto Alegre RS &#8211; 1\u00aa Mostra de Ov\u00e1is, na Galeria do Arco<\/li><li>1985 &#8211; Porto Alegre RS &#8211; Iber\u00ea Camargo: trajet\u00f3ria e encontros, no Margs<\/li><li>1985 &#8211; Porto Alegre RS &#8211; Pr\u00e9-Vis\u00e3o: ga\u00fachos na Bienal, na Galeria Tina Presser<\/li><li>1985 &#8211; Rio de Janeiro RJ &#8211; 8\u00ba Sal\u00e3o Nacional de Artes Pl\u00e1sticas, no MAM\/RJ<\/li><li>1985 &#8211; Rio de Janeiro RJ &#8211; Encontros, na Petite Galerie<\/li><li>1985 &#8211; Rio de Janeiro RJ &#8211; Seis D\u00e9cadas de Arte Moderna: Cole\u00e7\u00e3o Roberto Marinho, no Pa\u00e7o Imperial<\/li><li>1985 &#8211; S\u00e3o Paulo SP &#8211; 18\u00aa Bienal Interncional de S\u00e3o Paulo, na Funda\u00e7\u00e3o Bienal<\/li><li>1986 &#8211; Bras\u00edlia DF &#8211; Iber\u00ea Camargo: trajet\u00f3ria e encontros, no Teatro Nacional Cl\u00e1udio Santoro<\/li><li>1986 &#8211; Rio de Janeiro RJ &#8211; A Nova Flor de Abacate, Grupo Guignard-1943 e Os Dissidentes-1942, na Galeria de Arte Banerj<\/li><li>1986 &#8211; Rio de Janeiro RJ &#8211; Iber\u00ea Camargo: trajet\u00f3ria e encontros, no MAM\/RJ<\/li><li>1986 &#8211; Rio de Janeiro RJ &#8211; Sete D\u00e9cadas da Presen\u00e7a Italiana na Arte Brasileira, no Pa\u00e7o Imperial<\/li><li>1986 &#8211; S\u00e3o Paulo SP &#8211; Iber\u00ea Camargo: trajet\u00f3ria e encontros, no MAM\/SP<\/li><li>1987 &#8211; Paris (Fran\u00e7a) &#8211; Modernidade: arte brasileira do s\u00e9culo XX, no Mus\u00e9e d&#8217;Art Moderne de la Ville de Paris<\/li><li>1987 &#8211; Rio de Janeiro RJ &#8211; Ao Colecionador: homenagem a Gilberto Chateaubriand, no MAM\/RJ<\/li><li>1987 &#8211; Rio de Janeiro RJ &#8211; Rio de Janeiro, Fevereiro, Mar\u00e7o: do modernismo \u00e0 gera\u00e7\u00e3o 80, na Galeria de Arte Banerj<\/li><li>1987 &#8211; S\u00e3o Paulo SP &#8211; O Of\u00edcio da Arte: pintura, no Sesc<\/li><li>1988 &#8211; Ribeir\u00e3o Preto SP &#8211; L\u00edvio Abramo, Iber\u00ea Camargo e Amilcar de Castro, na Casa da Cultura<\/li><li>1988 &#8211; Rio de Janeiro RJ &#8211; O Tempo e o Vento, na Galeria de Arte Ipanema<\/li><li>1988 &#8211; Salvador BA &#8211; Os Ilustradores de Jorge Amado, na Funda\u00e7\u00e3o Casa de Jorge Amado<\/li><li>1988 &#8211; S\u00e3o Paulo SP &#8211; Modernidade: arte brasileira do s\u00e9culo XX, no MAM\/SP<\/li><li>1988 &#8211; S\u00e3o Paulo SP &#8211; Os Ritmos e as Formas: arte brasileira contempor\u00e2nea, no Sesc Pomp\u00e9ia<\/li><li>1989 &#8211; Copenhague (Dinamarca) &#8211; Os Ritmos e as Formas: arte brasileira contempor\u00e2nea, no Museu Charlottenborg<\/li><li>1989 &#8211; Fortaleza CE &#8211; Arte Brasileira dos S\u00e9culos XIX e XX nas Cole\u00e7\u00f5es Cearenses: pinturas e desenhos, no Espa\u00e7o Cultural da Unifor<\/li><li>1989 &#8211; Lisboa (Portugal) &#8211; Seis D\u00e9cadas de Arte Moderna Brasileira: Cole\u00e7\u00e3o Roberto Marinho, na Funda\u00e7\u00e3o Calouste Gulbenkian. Centro de Arte Moderna Jos\u00e9 de Azeredo Perdig\u00e3o<\/li><li>1989 &#8211; Porto Alegre RS &#8211; Arte Sul 89, no Margs<\/li><li>1989 &#8211; Porto Alegre RS &#8211; Galeria Tina Zappoli: 8\u00ba anivers\u00e1rio, na Galeria Tina Zappoli<\/li><li>1989 &#8211; Recife PE &#8211; Jogo de Mem\u00f3ria<\/li><li>1989 &#8211; Rio de Janeiro RJ &#8211; Gravura Brasileira: 4 temas, na EAV\/Parque Lage<\/li><li>1989 &#8211; Rio de Janeiro RJ &#8211; Jogo de Mem\u00f3ria, na Montesanti Galleria<\/li><li>1989 &#8211; Rio de Janeiro RJ &#8211; Rio Hoje, no MAM\/RJ<\/li><li>1989 &#8211; Rio de Janeiro RJ &#8211; Tina Zapolli visita Saramenha, na Galeria Saramenha<\/li><li>1989 &#8211; S\u00e3o Paulo SP &#8211; 20\u00aa Bienal Internacional de S\u00e3o Paulo, na Funda\u00e7\u00e3o Bienal<\/li><li>1989 &#8211; S\u00e3o Paulo SP &#8211; 20\u00ba Panorama de Arte Atual Brasileira, no MAM\/SP<\/li><li>1989 &#8211; S\u00e3o Paulo SP &#8211; Gesto e Estrutura, no Gabinete de Arte Raquel Arnaud<\/li><li>1989 &#8211; S\u00e3o Paulo SP &#8211; Jogo de Mem\u00f3ria, na Galeria Montesanti Roesler<\/li><li>1990 &#8211; Atami (Jap\u00e3o) 9\u00aa Exposi\u00e7\u00e3o Brasil-Jap\u00e3o de Arte Contempor\u00e2nea<\/li><li>1990 &#8211; Bras\u00edlia DF &#8211; 9\u00aa Exposi\u00e7\u00e3o Brasil-Jap\u00e3o de Arte Contempor\u00e2nea<\/li><li>1990 &#8211; Curitiba PR &#8211; 9\u00aa Mostra da Gravura Cidade de Curitiba, no Museu da Gravura<\/li><li>1990 &#8211; Porto Alegre RS &#8211; 1990: aos nossos artistas, na Galeria Tina Zappoli<\/li><li>1990 &#8211; Porto Alegre RS &#8211; 1\u00ba Sal\u00e3o Nacional de Arte Contempor\u00e2nea da UFRGS, no Museu Universit\u00e1rio da UFRGS<\/li><li>1990 &#8211; Rio de Janeiro RJ &#8211; 9\u00aa Exposi\u00e7\u00e3o Brasil-Jap\u00e3o de Arte Contempor\u00e2nea<\/li><li>1990 &#8211; Rio de Janeiro RJ &#8211; Ibeu: 1940 &#8211; 1990, na Galeria Ibeu Copacabana<\/li><li>1990 &#8211; Rio de Janeiro RJ &#8211; Primavera 90, na Galeria H. Stern<\/li><li>1990 &#8211; S\u00e3o Paulo SP &#8211; 9\u00aa Exposi\u00e7\u00e3o Brasil-Jap\u00e3o de Arte Contempor\u00e2nea, na Funda\u00e7\u00e3o Brasil-Jap\u00e3o<\/li><li>1990 &#8211; Sapporo (Jap\u00e3o) 9\u00aa Exposi\u00e7\u00e3o Brasil-Jap\u00e3o de Arte Contempor\u00e2nea<\/li><li>1990 &#8211; T\u00f3quio (Jap\u00e3o) 9\u00aa Exposi\u00e7\u00e3o Brasil-Jap\u00e3o de Arte Contempor\u00e2nea<\/li><li>1991 &#8211; Rio de Janeiro RJ &#8211; M\u00e1rio Pedrosa, Arte, Revolu\u00e7\u00e3o e Reflex\u00e3o, no CCBB<\/li><li>1991 &#8211; S\u00e3o Paulo SP &#8211; A \u00c1rvore de Cada Um, na Galeria Nara Roesler<\/li><li>1991 &#8211; S\u00e3o Paulo SP &#8211; Sobre a \u00c1rvore, na Galeria Montesanti Roesler<\/li><li>1991 &#8211; S\u00e3o Paulo SP &#8211; Sobre o Branco, na Galeria de Arte S\u00e3o Paulo<\/li><li>1992 &#8211; Cachoeira do Sul RS &#8211; Francisco Stockinger e Iber\u00ea Camargo<\/li><li>1992 &#8211; Curitiba PR &#8211; 10\u00aa Mostra da Gravura Cidade de Curitiba\/Mostra Am\u00e9rica, no Museu da Gravura<\/li><li>1992 &#8211; Po\u00e7os de Caldas MG &#8211; Arte Moderna Brasileira: acervo do Museu de Arte Contempor\u00e2nea da Universidade de S\u00e3o Paulo, na Casa da Cultura<\/li><li>1992 &#8211; Porto Alegre RS &#8211; 1992, na Galeria Tina Zappoli<\/li><li>1992 &#8211; Porto Alegre RS &#8211; Arte Contempor\u00e2nea: destaques do Sul, no Espa\u00e7o Cultural Edel Trade Center<\/li><li>1992 &#8211; Porto Alegre RS &#8211; Hist\u00f3ricos, no Margs<\/li><li>1992 &#8211; Porto Alegre RS &#8211; M\u00e1rio Pedrosa, Arte, Revolu\u00e7\u00e3o e Reflex\u00e3o, no Centro Municipal de Cultura<\/li><li>1992 &#8211; Rio de Janeiro RJ &#8211; 1\u00ba A Caminho de Niter\u00f3i: Cole\u00e7\u00e3o Jo\u00e3o Sattamini, no Pa\u00e7o Imperial<\/li><li>1992 &#8211; Rio de Janeiro RJ &#8211; De Debret a Iber\u00ea, no Museu da Cidade<\/li><li>1992 &#8211; Rio de Janeiro RJ &#8211; Gravura de Arte no Brasil: proposta para um mapeamento, no CCBB<\/li><li>1992 &#8211; Rio de Janeiro RJ &#8211; Natureza: quatro s\u00e9culos de arte no Brasil, no CCBB<\/li><li>1992 &#8211; S\u00e3o Paulo SP &#8211; Branco Dominante, na Galeria de Arte S\u00e3o Paulo<\/li><li>1993 &#8211; Fortaleza CE &#8211; 23 Anos, na Galeria Ignez Fiuza<\/li><li>1993 &#8211; Niter\u00f3i RJ &#8211; 2\u00ba A Caminho de Niter\u00f3i: Cole\u00e7\u00e3o Jo\u00e3o Sattamini, no MAC\/Niter\u00f3i<\/li><li>1993 &#8211; Porto Alegre RS &#8211; 1993, na Galeria Tina Zappoli<\/li><li>1993 &#8211; Rio de Janeiro RJ &#8211; Arte Er\u00f3tica, no MAM\/RJ<\/li><li>1993 &#8211; Rio de Janeiro RJ &#8211; Brasil, 100 Anos de Arte Moderna, no MNBA<\/li><li>1993 &#8211; Rio de Janeiro RJ &#8211; Emblemas do Corpo: o nu na arte moderna brasileira, no CCBB<\/li><li>1993 &#8211; Rio de Janeiro RJ &#8211; Gravuras de Amilcar de Castro, Antonio Dias, Iber\u00ea Camargo e S\u00e9rgio Fingermann, na EAV\/Parque Lage<\/li><li>1993 &#8211; S\u00e3o Paulo SP &#8211; Po\u00e9tica, no Gabinete de Arte Raquel Arnaud<\/li><li>1994 &#8211; Porto Alegre RS &#8211; 1994, na Galeria Tina Zappoli<\/li><li>1994 &#8211; Porto Alegre RS &#8211; Zero Hora 30 Anos, na Ag\u00eancia de Arte<\/li><li>1994 &#8211; S\u00e3o Paulo SP &#8211; Arte Moderna Brasileira: uma sele\u00e7\u00e3o da Cole\u00e7\u00e3o Roberto Marinho, no Masp<\/li><li>1994 &#8211; S\u00e3o Paulo SP &#8211; Bienal Brasil S\u00e9culo XX, na Funda\u00e7\u00e3o Bienal<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>EXPOSI\u00c7\u00d5ES P\u00d3STUMAS<\/strong><\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>1994 &#8211; Po\u00e7os de Caldas MG &#8211; Cole\u00e7\u00e3o Unibanco: exposi\u00e7\u00e3o comemorativa dos 70 anos de Unibanco, na Casa da Cultura<\/li><li>1994 &#8211; Porto Alegre RS &#8211; Iber\u00ea Camargo Mestre Moderno, na Galeria Iber\u00ea Camargo<\/li><li>1994 &#8211; Porto Alegre RS &#8211; Iber\u00ea Camargo: desenhos e gravuras em metal, na Galeria Tina Zappoli<\/li><li>1994 &#8211; Rio de Janeiro RJ &#8211; Trincheiras: arte e pol\u00edtica no Brasil, no MAM\/RJ<\/li><li>1994 &#8211; S\u00e3o Paulo SP &#8211; 22\u00aa Bienal Internacional de S\u00e3o Paulo, na Funda\u00e7\u00e3o Bienal<\/li><li>1994 &#8211; S\u00e3o Paulo SP &#8211; Po\u00e9tica da Resist\u00eancia: aspectos da gravura brasileira, na Galeria de Arte do Sesi<\/li><li>1995 &#8211; Bras\u00edlia DF &#8211; Cole\u00e7\u00f5es de Bras\u00edlia, no Minist\u00e9rio das Rela\u00e7\u00f5es Exteriores. Pal\u00e1cio do Itamaraty<\/li><li>1995 &#8211; Bras\u00edlia DF &#8211; Cole\u00e7\u00f5es de Bras\u00edlia, no Minist\u00e9rio das Rela\u00e7\u00f5es Exteriores. Pal\u00e1cio do Itamaraty<\/li><li>1995 &#8211; Londrina PR &#8211; Arte Brasileira: confrontos e contrastes, no Pavilh\u00e3o Internacional Oct\u00e1vio Ces\u00e1rio Pereira J\u00fanior<\/li><li>1995 &#8211; Rio de Janeiro RJ &#8211; Cole\u00e7\u00e3o Unibanco: exposi\u00e7\u00e3o comemorativa dos 70 anos do Unibanco, no MAM\/RJ<\/li><li>1995 &#8211; S\u00e3o Paulo SP &#8211; Morandi no Brasil, no CCSP<\/li><li>1996 &#8211; Barra Mansa RJ &#8211; 12 Nomes da Pintura Brasileira, no Centro Universit\u00e1rio<\/li><li>1996 &#8211; Belo Horizonte MG &#8211; Impress\u00f5es Itinerantes, no Pal\u00e1cio das Artes<\/li><li>1996 &#8211; Curitiba PR &#8211; Individual, na Galeria Max Stolz<\/li><li>1996 &#8211; Niter\u00f3i RJ &#8211; Arte Contempor\u00e2nea Brasileira na Cole\u00e7\u00e3o Jo\u00e3o Sattamini, no MAC\/Niter\u00f3i<\/li><li>1996 &#8211; Niter\u00f3i RJ &#8211; Individual, na UFF<\/li><li>1996 &#8211; Porto Alegre RS &#8211; Natureza Humana, na Galeria Tina Zappoli<\/li><li>1996 &#8211; Rio de Janeiro RJ &#8211; O Grito, no MNBA<\/li><li>1996 &#8211; S\u00e3o Paulo SP &#8211; Arte Brasileira: 50 anos de hist\u00f3ria no acervo MAC\/USP: 1920-1970, no MAC\/USP<\/li><li>1996 &#8211; S\u00e3o Paulo SP &#8211; Figura e Paisagem no Acervo do MAM: homenagem a Volpi, no MAM\/SP<\/li><li>1997 &#8211; Barra Mansa RJ &#8211; O Museu Visita a Galeria, no Centro Universit\u00e1rio<\/li><li>1997 &#8211; Curitiba PR &#8211; A Arte Contempor\u00e2nea da Gravura, no Museu Metropolitano de Arte de Curitiba<\/li><li>1997 &#8211; Porto Alegre RS &#8211; Individual, na Galeria Cezar Prestes Arte<\/li><li>1997 &#8211; S\u00e3o Paulo SP &#8211; Exposi\u00e7\u00e3o Inaugural, no Brito Cimino Arte Contempor\u00e2nea e Moderna<\/li><li>1998 &#8211; Niter\u00f3i RJ &#8211; Espelho da Bienal, no MAC\/Niter\u00f3i<\/li><li>1998 &#8211; Rio de Janeiro RJ &#8211; Arte Brasileira no Acervo do Museu de Arte Moderna de S\u00e3o Paulo: doa\u00e7\u00f5es recentes 1996-1998, no CCBB<\/li><li>1998 &#8211; S\u00e3o Paulo SP &#8211; A Arte de Expor Arte, no MAM\/SP<\/li><li>1998 &#8211; S\u00e3o Paulo SP &#8211; Afinidades Eletivas I: o olhar do colecionador, na Casa das Rosas<\/li><li>1998 &#8211; S\u00e3o Paulo SP &#8211; Cole\u00e7\u00e3o MAM Bahia: pinturas, no MAM\/SP<\/li><li>1998 &#8211; S\u00e3o Paulo SP &#8211; Destaques da Cole\u00e7\u00e3o Unibanco, no Instituto Moreira Salles<\/li><li>1998 &#8211; S\u00e3o Paulo SP &#8211; O Moderno e o Contempor\u00e2neo na Arte Brasileira: Cole\u00e7\u00e3o Gilberto Chateaubriand &#8211; MAM\/RJ , no Masp<\/li><li>1998 &#8211; S\u00e3o Paulo SP &#8211; Os Colecionadores &#8211; Guita e Jos\u00e9 Mindlin: matrizes e gravuras, na Galeria de Arte do Sesi<\/li><li>1999 &#8211; Niter\u00f3i RJ &#8211; Mostra Rio Gravura. Acervo Banerj, no Museu do Ing\u00e1<\/li><li>1999 &#8211; Porto Alegre RS &#8211; 2\u00aa Bienal de Artes Visuais do Mercosul, na Funda\u00e7\u00e3o Bienal de Artes Visuais do Mercosul<\/li><li>1999 &#8211; Porto Alegre RS &#8211; Garagem de Arte: mostra inaugural, na Garagem de Arte<\/li><li>1999 &#8211; Porto Alegre RS &#8211; Individual, no Margs<\/li><li>1999 &#8211; Porto Alegre RS &#8211; Primeira Mostra da Funda\u00e7\u00e3o Iber\u00ea Camargo, na Funda\u00e7\u00e3o Iber\u00ea Camargo<\/li><li>1999 &#8211; Rio de Janeiro RJ &#8211; Mostra Rio Gravura. Gravura Moderna Brasileira: acervo Museu Nacional de Belas Artes, no MNBA<\/li><li>1999 &#8211; S\u00e3o Paulo SP &#8211; Arte Brasileira, S\u00e9culo XX: di\u00e1logos com Dufy, no MAM\/SP<\/li><li>1999 &#8211; S\u00e3o Paulo SP &#8211; Cotidiano\/Arte. O Consumo, no Ita\u00fa Cultural<\/li><li>2000 &#8211; Bras\u00edlia DF &#8211; Exposi\u00e7\u00e3o Brasil Europa: encontros no s\u00e9culo XX, no Conjunto Cultural da Caixa<\/li><li>2000 &#8211; Caxias do Sul RS &#8211; Mostra Itinerante do Acervo do Margs<\/li><li>2000 &#8211; Curitiba PR &#8211; 12\u00aa Mostra da Gravura de Curitiba. Marcas do Corpo, Dobras da Alma<\/li><li>2000 &#8211; Lisboa (Portugal) &#8211; S\u00e9culo 20: arte do Brasil, na Funda\u00e7\u00e3o Calouste Gulbenkian. Centro de Arte Moderna Jos\u00e9 de Azeredo Perdig\u00e3o<\/li><li>2000 &#8211; Niter\u00f3i RJ &#8211; Pinturas na Cole\u00e7\u00e3o Jo\u00e3o Sattamini, no MAC\/Niter\u00f3i<\/li><li>2000 &#8211; Passo Fundo RS &#8211; Mostra Itinerante do Acervo do Margs<\/li><li>2000 &#8211; Pelotas RS &#8211; Mostra Itinerante do Acervo do Margs<\/li><li>2000 &#8211; Porto Alegre RS &#8211; Iber\u00ea Camargo: caminhos de uma po\u00e9tica, na Funda\u00e7\u00e3o Iber\u00ea Camargo<\/li><li>2000 &#8211; Rio de Janeiro RJ &#8211; Quando o Brasil era Moderno: artes pl\u00e1sticas no Rio de Janeiro de 1905 a 1960, no Pa\u00e7o Imperial<\/li><li>2000 &#8211; Santa Maria RS &#8211; Mostra Itinerante do Acervo do Margs<\/li><li>2000 &#8211; S\u00e3o Paulo SP &#8211; A Figura Humana na Cole\u00e7\u00e3o Ita\u00fa, no Ita\u00fa Cultural<\/li><li>2000 &#8211; S\u00e3o Paulo SP &#8211; Brasil + 500 Mostra do Redescobrimento, na Funda\u00e7\u00e3o Bienal<\/li><li>2000 &#8211; S\u00e3o Paulo SP &#8211; Investiga\u00e7\u00f5es. A Gravura Brasileira, no Ita\u00fa Cultural<\/li><li>2000 &#8211; S\u00e3o Paulo SP &#8211; O Papel da Arte, na Galeria de Arte do Sesi<\/li><li>2001 &#8211; Bras\u00edlia DF &#8211; Investiga\u00e7\u00f5es. A Gravura Brasileira, na Galeria Ita\u00fa Cultural<\/li><li>2001 &#8211; Pen\u00e1polis SP &#8211; Investiga\u00e7\u00f5es. A Gravura Brasileira, na Galeria Ita\u00fa Cultural<\/li><li>2001 &#8211; Porto Alegre RS &#8211; Cole\u00e7\u00e3o Liba e Rubem Knijnik: arte brasileira contempor\u00e2nea, no Margs<\/li><li>2001 &#8211; Porto Alegre RS &#8211; Iber\u00ea Camargo: um exerc\u00edcio do olhar, na Funda\u00e7\u00e3o Iber\u00ea Camargo<\/li><li>2001 &#8211; Rio de Janeiro RJ &#8211; Acervo da Arte Carioca, na Galeria de Arte Ipanema<\/li><li>2001 &#8211; Rio de Janeiro RJ &#8211; Aquarela Brasileira, no Centro Cultural Light<\/li><li>2001 &#8211; Rio de Janeiro RJ &#8211; Cole\u00e7\u00f5es do Moderno: Hecilda e Sergio Fadel na Ch\u00e1cara do C\u00e9u, nos Museus Castro Maya. Museu da Ch\u00e1cara do C\u00e9u<\/li><li>2001 &#8211; Rio de Janeiro RJ &#8211; O Esp\u00edrito de Nossa \u00c9poca, no MAM\/RJ<\/li><li>2001 &#8211; Rio de Janeiro RJ &#8211; Trilhando a Gravura, no Museu da Ch\u00e1cara do C\u00e9u<\/li><li>2001 &#8211; S\u00e3o Paulo SP &#8211; Iber\u00ea Camargo: retrospectiva, na Galeria Millan<\/li><li>2001 &#8211; S\u00e3o Paulo SP &#8211; O Esp\u00edrito de Nossa \u00c9poca, no MAM\/SP<\/li><li>2001 &#8211; S\u00e3o Paulo SP &#8211; Trajet\u00f3ria da Luz na Arte Brasileira, no Ita\u00fa Cultural<\/li><li>2002 &#8211; Bras\u00edlia DF &#8211; Fragmentos a Seu \u00cdm\u00e3, no Espa\u00e7o Cultural Contempor\u00e2neo Ven\u00e2ncio<\/li><li>2002 &#8211; Niter\u00f3i RJ &#8211; Arte Brasileira sobre Papel: s\u00e9culos XIX e XX, no Solar do Jambeiro<\/li><li>2002 &#8211; Niter\u00f3i RJ &#8211; Cole\u00e7\u00e3o Sattamini: modernos e contempor\u00e2neos, no MAC\/Niter\u00f3i<\/li><li>2002 &#8211; Niter\u00f3i RJ &#8211; Di\u00e1logo, Antagonismo e Replica\u00e7\u00e3o na Cole\u00e7\u00e3o Sattamini, no MAC\/Niter\u00f3i<\/li><li>2002 &#8211; Porto Alegre RS &#8211; Desenhos, Gravuras, Esculturas e Aquarelas, na Garagem de Arte<\/li><li>2002 &#8211; Porto Alegre RS &#8211; Retrato: um olhar al\u00e9m do tempo, na Funda\u00e7\u00e3o Iber\u00ea Camargo<\/li><li>2002 &#8211; Porto Alegre RS &#8211; Viol\u00eancia e Paix\u00e3o, no Santader Cultural<\/li><li>2002 &#8211; Rio de Janeiro RJ &#8211; 1\u00aa Mostra Rio Arte Contempor\u00e2nea, no MAM\/RJ<\/li><li>2002 &#8211; Rio de Janeiro RJ &#8211; Arte Brasileira na Cole\u00e7\u00e3o Fadel: da inquieta\u00e7\u00e3o do moderno \u00e0 autonomia da linguagem, no CCBB<\/li><li>2002 &#8211; Rio de Janeiro RJ &#8211; Caminhos do Contempor\u00e2neo 1952-2002, no Pa\u00e7o Imperial<\/li><li>2002 &#8211; Rio de Janeiro RJ &#8211; Individual, na Bolsa de Arte do Rio de Janeiro<\/li><li>2002 &#8211; S\u00e3o Paulo SP &#8211; 28 (+) Pintura, no Espa\u00e7o Virg\u00edlio<\/li><li>2002 &#8211; S\u00e3o Paulo SP &#8211; Arte Brasileira na Cole\u00e7\u00e3o Fadel: da inquieta\u00e7\u00e3o do moderno \u00e0 autonomia da linguagem, no CCBB<\/li><li>2002 &#8211; S\u00e3o Paulo SP &#8211; Mapa do Agora: arte brasileira recente na Cole\u00e7\u00e3o Jo\u00e3o Sattamini do Museu de Arte Contempor\u00e2nea de Niter\u00f3i, no Instituto Tomie Ohtake<\/li><li>2003 &#8211; Bras\u00edlia DF &#8211; Arte Brasileira na Cole\u00e7\u00e3o Fadel: da inquieta\u00e7\u00e3o do moderno \u00e0 autonomia da linguagem, no CCBB<\/li><li>2003 &#8211; Porto Alegre RS &#8211; Humanidades, na Galeria Tina Zappoli<\/li><li>2003 &#8211; Rio de Janeiro RJ &#8211; Arte Brasileira: da Revolu\u00e7\u00e3o de 30 ao p\u00f3s-guerra, no MAM\/RJ<\/li><li>2003 &#8211; Rio de Janeiro RJ &#8211; Arte em Movimento, no Espa\u00e7o BNDES<\/li><li>2003 &#8211; Rio de Janeiro RJ &#8211; Iber\u00ea Camargo: diante da pintura, no Pa\u00e7o Imperial<\/li><li>2003 &#8211; Rio de Janeiro RJ &#8211; Ordem x Liberdade, no MAM\/RJ<\/li><li>2003 &#8211; S\u00e3o Paulo SP &#8211; A Gravura Vai Bem, Obrigado: a gravura hist\u00f3rica e contempor\u00e2nea brasileira, no Espa\u00e7o Virg\u00edlio<\/li><li>2003 &#8211; S\u00e3o Paulo SP &#8211; Iber\u00ea Camargo: diante da pintura, na Pinacoteca do Estado<\/li><li>2003 &#8211; S\u00e3o Paulo SP &#8211; MAC USP 40 Anos: interfaces contempor\u00e2neas, no MAC\/USP<\/li><li>2003 &#8211; S\u00e3o Paulo SP &#8211; Natureza Morta, no Espa\u00e7o Cultural BM&amp;F<\/li><li>2003 &#8211; S\u00e3o Paulo SP &#8211; Papel e Tridimensional, na Arvani Arte<\/li><li>2004 &#8211; Belo Horizonte MG &#8211; Pampulha, Obra Colecionada: 1943-2003, no MAP<\/li><li>2004 &#8211; Mariana MG &#8211; Individual, na Galeria Sesi<\/li><li>2004 &#8211; Niter\u00f3i RJ &#8211; Modernidade Transitiva, no MAC\/Niter\u00f3i<\/li><li>2004 &#8211; Ouro Preto MG &#8211; Iber\u00ea Gravura, no Museu da Inconfid\u00eancia<\/li><li>2004 &#8211; Rio de Janeiro RJ &#8211; O S\u00e9culo de um Brasileiro: Cole\u00e7\u00e3o Roberto Marinho, no Pa\u00e7o Imperial<\/li><li>2004 &#8211; S\u00e3o Paulo SP &#8211; Abstra\u00e7\u00e3o como Linguagem: perfil de um acervo, na Pinakotheke<\/li><li>2004 &#8211; S\u00e3o Paulo SP &#8211; Arte Contempor\u00e2nea no Ateli\u00ea de Iber\u00ea Camargo, no Centro Universit\u00e1rio Maria Antonia<\/li><li>2004 &#8211; S\u00e3o Paulo SP &#8211; Gesto e Express\u00e3o: o abstracionismo informal nas cole\u00e7\u00f5es JP Morgan Chase e MAM, no MAM\/SP<\/li><li>2005 &#8211; S\u00e3o Paulo SP &#8211; O S\u00e9culo de um Brasileiro: Cole\u00e7\u00e3o Roberto Marinho, no MAM\/SP<\/li><li>2005 &#8211; Iber\u00ea: Ciclistas e Outras Varia\u00e7\u00f5es &#8211; Museu de Belas Artes de Bordeaux (Fran\u00e7a) &#8211; Per\u00edodo: mar\u00e7o a maio de 2005<\/li><li>2005 &#8211; Iber\u00ea Camargo: Pintura Pura &#8211; Per\u00edodo: mar\u00e7o de 2004 a mar\u00e7o de 2005<\/li><li>2006 &#8211; Gravura em metal: mat\u00e9ria e conceito no Ateli\u00ea de Iber\u00ea Camargo &#8211; Centro Municipal de Cultura Dr. Henrique Ordov\u00e1s Filho (Caxias do Sul, RS) &#8211; Per\u00edodo: 3 de agosto a 10 de setembro de 2006<\/li><li>2006 &#8211; Iber\u00ea Camargo &#8211; Galeria de Arte Ipanema &#8211; Inaugura\u00e7\u00e3o: 19 de setembro 2006<\/li><li>2007 &#8211; Iber\u00ea Camargo e as proje\u00e7\u00f5es de um ateli\u00ea no tempo &#8211; Museu de Artes do Rio Grande do Sul Per\u00edodo: 05 de junho de 2007 a 05 de agosto de 2007<\/li><li>2008 &#8211; Gravuras de Iber\u00ea Camargo. Percursos e aproxima\u00e7\u00f5es em uma po\u00e9tica &#8211; Palacete das Artes \u2013 Rodin Bahia (Salvador) &#8211; Per\u00edodo: 13 de novembro de 2007 a 20 de janeiro de 2008<\/li><\/ul>","protected":false},"excerpt":{"rendered":"<p>BIOGRAFIA Iber\u00ea Bassani de Camargo (Restinga Seca RS 1914 &#8211; Porto Alegre RS 1994). Pintor, gravador, desenhista, escritor e professor. Em 1928 estuda pintura com Frederico Lobe e Salvador Parlagreco (1871 &#8211; 1953) na Escola de Artes e Of\u00edcios, em Santa Maria, Rio Grande do Sul. Entre 1936 e 1939, em Porto Alegre, faz o &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/galeria-ipanema.com\/en\/ibere-camargo\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Iber\u00ea Camargo&#8221;<\/span><\/a><\/p>","protected":false},"author":178370742,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","_crdt_document":"","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"footnotes":""},"class_list":["post-1983","page","type-page","status-publish","hentry"],"jetpack_likes_enabled":false,"jetpack_sharing_enabled":false,"jetpack_shortlink":"https:\/\/wp.me\/PbBA92-vZ","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/galeria-ipanema.com\/en\/wp-json\/wp\/v2\/pages\/1983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galeria-ipanema.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/galeria-ipanema.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/galeria-ipanema.com\/en\/wp-json\/wp\/v2\/users\/178370742"}],"replies":[{"embeddable":true,"href":"https:\/\/galeria-ipanema.com\/en\/wp-json\/wp\/v2\/comments?post=1983"}],"version-history":[{"count":1,"href":"https:\/\/galeria-ipanema.com\/en\/wp-json\/wp\/v2\/pages\/1983\/revisions"}],"predecessor-version":[{"id":1986,"href":"https:\/\/galeria-ipanema.com\/en\/wp-json\/wp\/v2\/pages\/1983\/revisions\/1986"}],"wp:attachment":[{"href":"https:\/\/galeria-ipanema.com\/en\/wp-json\/wp\/v2\/media?parent=1983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}